{"id":1,"count":412,"description":"","link":"https:\/\/kunstinargentinien.com\/index.php\/category\/allgemein-general\/","name":"Allgemein \/ General","slug":"allgemein-general","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/kunstinargentinien.com\/index.php\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstinargentinien.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kunstinargentinien.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kunstinargentinien.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}